{"id":19,"date":"2018-12-19T07:30:25","date_gmt":"2018-12-19T07:30:25","guid":{"rendered":"http:\/\/res01.wp.portals.vn\/?page_id=19"},"modified":"2022-10-22T13:00:09","modified_gmt":"2022-10-22T13:00:09","slug":"about-us","status":"publish","type":"page","link":"https:\/\/tnspcflooring.ca\/fr\/home-slider\/about-us\/","title":{"rendered":"\u00c0 PROPOS DE NOUS"},"content":{"rendered":"<div class=\"banner has-hover\" id=\"banner-416344486\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div><!-- bg-layers -->\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1036864252\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase heard\">\u00c0 PROPOS DE NOUS<\/h3>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-384 aligncenter\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2019\/10\/breadcrum.png\" alt=\"\" width=\"692\" height=\"25\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2019\/10\/breadcrum.png 692w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2019\/10\/breadcrum-600x22.png 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2019\/10\/breadcrum-300x11.png 300w\" sizes=\"(max-width: 692px) 100vw, 692px\" \/><\/p>\n              <\/div>\n           <\/div><!-- text-box-inner -->\n                            \n<style scope=\"scope\">\n\n#text-box-1036864252 {\n  width: 71%;\n}\n#text-box-1036864252 .text {\n  font-size: 100%;\n}\n<\/style>\n    <\/div><!-- text-box -->\n \n        <\/div><!-- .banner-layers -->\n      <\/div><!-- .banner-inner -->\n\n              <div class=\"height-fix is-invisible\"><img width=\"1350\" height=\"229\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2019\/10\/bg_gioithieu.png\" class=\"attachment-orginal size-orginal\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2019\/10\/bg_gioithieu.png 1350w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2019\/10\/bg_gioithieu-600x102.png 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2019\/10\/bg_gioithieu-300x51.png 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2019\/10\/bg_gioithieu-768x130.png 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2019\/10\/bg_gioithieu-1024x174.png 1024w\" sizes=\"(max-width: 1350px) 100vw, 1350px\" \/><\/div>\n            \n<style scope=\"scope\">\n\n#banner-416344486 .bg.bg-loaded {\n  background-image: url(https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2019\/10\/bg_gioithieu.png);\n}\n#banner-416344486 .overlay {\n  background-color: rgba(0, 0, 0, 0.17);\n}\n<\/style>\n  <\/div><!-- .banner -->\n\n\n<div class=\"about-us\">\n<div id=\"ve-tinan\" class=\"ve-tinan\">\n<div class=\"about-head wow fadeInUp\" data-wow-offset=\"0\" data-wow-duration=\"1\" data-wow-delay=\"0.2s\">\n<div class=\"container\">\n<h2><span class=\"bd-right\">\u00c0 PROPOS DE TIN AN JSC<\/span><\/h2>\n<\/div>\n<\/div>\n<div class=\"container\">\n<div class=\"about-content\">\n<div class=\"item\">\n<div class=\"content-left wow bounceInLeft\" data-wow-delay=\"1s\">\n<div class=\"text bd-left\">\n<p><b>TIN AN JSC<\/b>&nbsp;a \u00e9t\u00e9 cr\u00e9\u00e9e fin 2016, avec un capital social de 250 milliards de dongs vietnamiens, la superficie totale au sol pouvant atteindre 60 000 m2. Les produits strat\u00e9giques de l'entreprise comprennent les rev\u00eatements de sol<b><i>&nbsp;SPC<\/i><\/b>&nbsp;<b><i>SPC  , les produits pour le traitement des exportations vers le march\u00e9 am\u00e9ricain, les portes et fen\u00eatres en plastique\/aluminium \u00e0 noyau d'acier, la fa\u00e7ade, la fourniture de solutions et de services de construction, l'installation pour les travaux de construction.<\/i><\/b><\/p>\n<\/div>\n<\/div>\n<div class=\"content-right wow bounceInRight\" data-wow-delay=\"1.5s\"><img decoding=\"async\" src=\"https:\/\/tinanjsc.com\/upload\/news\/295872659341_830x455.jpg\" alt=\"\"><\/div>\n<\/div>\n<div class=\"item rtl\">\n<div class=\"content-left wow bounceInLeft\" data-wow-delay=\"1s\">\n<div class=\"text bd-left\">\n<p class=\" translation-block\">Tin An est fier d'\u00eatre le pionnier du Vietnam \u00e0 signer l'accord de coop\u00e9ration de Click Technology de Valinge - Su\u00e8de. Avec une infrastructure compl\u00e8te, une ligne de production automatis\u00e9e, un laboratoire moderne et un syst\u00e8me de gestion de la qualit\u00e9\u00a0<strong>ISO 9001\u00a0: 2015, ISO 14001\u00a0: 2015<\/strong>\u2026 Tin An's SPC Flooring obtient des certificats internationaux et satisfait avec succ\u00e8s les march\u00e9s les plus difficiles d'Am\u00e9rique du Nord et L'Europe .<\/p>\n<p class=\" translation-block\">Avec une \u00e9quipe de jeunes employ\u00e9s ayant beaucoup d'enthousiasme combin\u00e9 \u00e0 la\u00a0strat\u00e9gie de d\u00e9veloppement commercial durable de la direction, Tin An s'est fix\u00e9 pour objectif de devenir l'un des <strong>\u00a0<em>SPC<\/em><\/strong>\u00a0<strong>\u00a0<em>SPC<\/em><\/strong>\u00a0<strong><em>Planchers, portes et fen\u00eatres en plastique\/aluminium \u00e0 noyau d'acier, fa\u00e7ade et produits OEM<\/em>s<\/strong>\u00a0au Vietnam au cours des 3\u00a0prochaines ann\u00e9es.<\/p>\n<\/div>\n<\/div>\n<div class=\"content-right wow bounceInRight\" data-wow-delay=\"1.5s\"><img decoding=\"async\" src=\"https:\/\/tinanjsc.com\/upload\/news\/441728978284_830x455.png\" alt=\"B\u00e0i vi\u1ebft 01\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"ve-daychuyen\" class=\"ve-daychuyen\">\n<div class=\"about-head wow fadeInUp\" data-wow-offset=\"0\" data-wow-duration=\"1\" data-wow-delay=\"0.2s\">\n<div class=\"container\">\n<h2><span class=\"bd-left\">NOTRE LIGNE DE PRODUCTION<\/span><\/h2>\n<\/div>\n<\/div>\n<div class=\"container\">\n<div class=\"about-content\">\n<div class=\"item\">\n<div class=\"content-left wow bounceInLeft\" data-wow-delay=\"1s\">\n<div class=\"text bd-left\">\n<p class=\" translation-block\">Le si\u00e8ge social de <strong>DURADOOR<\/strong> est \u00e9tabli dans le parc industriel de Dong An 2, province de Binh Duong. Il se compose de bureaux, d'un entrep\u00f4t, d'une usine, d'un campus vert avec plus de 60 000 m2 de surface qui r\u00e9pondent bien \u00e0 la demande des employ\u00e9s, respectueux de l'environnement.<\/p>\n<p>\u00c0 l'heure actuelle, la soci\u00e9t\u00e9 a investi dans des installations dot\u00e9es d'\u00e9quipements de pointe et de lignes de production modernes import\u00e9es d'Allemagne (SCHUECO, URBAN) pour la production et r\u00e9pondre \u00e0 toutes les exigences des clients nationaux et \u00e9trangers.<\/p>\n<\/div>\n<\/div>\n<div class=\"content-right wow bounceInRight\" data-wow-delay=\"1.5s\"><img decoding=\"async\" src=\"https:\/\/tinanjsc.com\/upload\/news\/143673547938_830x455.jpg\" alt=\"PRODUCTION LINE\"><\/div>\n<\/div>\n<div class=\"item rtl\">\n<div class=\"content-left wow bounceInLeft\" data-wow-delay=\"1s\">\n<div class=\"text bd-left\">\n<p class=\" translation-block\"><strong>Tin An JSC<\/strong>\u00a0a pr\u00e9vu une zone de 30\u00a0000\u00a0m\u00e8tres carr\u00e9s pour la fabrication de rev\u00eatements de sol SPC. Nous avons investi dans des syst\u00e8mes de machines \u00e0 grande capacit\u00e9 et \u00e0 la pointe de la technologie au Vietnam.<\/p>\n<p><strong>Tin An JSC<\/strong>\u00a0a pr\u00e9vu une zone de 30\u00a0000\u00a0m\u00e8tres carr\u00e9s pour la fabrication de rev\u00eatements de sol SPC. Nous avons investi dans des syst\u00e8mes de machines \u00e0 grande capacit\u00e9 et \u00e0 la pointe de la technologie au Vietnam.<\/p>\n<\/div>\n<\/div>\n<div class=\"content-right wow bounceInRight\" data-wow-delay=\"1.5s\"><img decoding=\"async\" src=\"https:\/\/tinanjsc.com\/upload\/news\/150955410223_830x455.jpg\" alt=\"PRODUCTION LINE\"><\/div>\n<\/div>\n<div class=\"item\">\n<div class=\"content-left wow bounceInLeft\" data-wow-delay=\"1s\">\n<div class=\"text bd-left\">\n<p class=\" translation-block\">Avec plus de 20 ans d'exp\u00e9rience dans l'industrie du PVC avec la ligne directrice\u00a0<strong>\"CONFIANCE - QUALIT\u00c9 - D\u00c9VELOPPEMENT NON-STOP\"<\/strong>, TIN AN est fier d'\u00eatre l'un des principaux fabricants de plastique au Vietnam qui se distinguent en tant que produits OEM . Il existe des produits tels que seuil \/ seuil de porte, garniture de carrelage, balai de porte, cl\u00f4ture en PVC, etc. Avec un total de 28 lignes d'extrusion et 4 lignes d'injection ainsi qu'un personnel professionnel et exp\u00e9riment\u00e9, nous avons fait une marque \u00e0 travers une gamme de OEM des produits de qualit\u00e9 qui r\u00e9pondent aux attentes des clients nationaux et \u00e0 l'internationalisation depuis de nombreuses ann\u00e9es.<\/p>\n<\/div>\n<\/div>\n<div class=\"content-right wow bounceInRight\" data-wow-delay=\"1.5s\"><img decoding=\"async\" src=\"https:\/\/tinanjsc.com\/upload\/news\/976045604938_830x455.jpg\" alt=\"OEM PRODUCTION LINE\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"he-thong\" class=\"he-thong\">\n<div class=\"about-head wow fadeInUp\" data-wow-offset=\"0\" data-wow-duration=\"1\" data-wow-delay=\"0.2s\">\n<div class=\"container\">\n<h2><span class=\"bd-right\">NOS ACTIVIT\u00c9S<\/span><\/h2>\n<\/div>\n<\/div>\n<div class=\"container\">\n<div class=\"about-content\">\n<div class=\"item\">\n<div class=\"content-left wow bounceInLeft\" data-wow-delay=\"1s\">\n<h3>INAUGURATION DU PONT VINH THAI<\/h3>\n<div class=\"text bd-left\">\n<p>Le 31 mai 2020, Tin An JSC \u00e9tait pr\u00e9sent aux hameaux 6 et 7, commune de Thoi Hung, district de Co Do, ville de Can Tho pour c\u00e9l\u00e9brer l'inauguration du pont Vinh Thai (pont Tu Tam 61). Avec un co\u00fbt total de construction de 275 millions de VND<\/p>\n<\/div>\n<\/div>\n<div class=\"content-right wow bounceInRight\" data-wow-delay=\"1.5s\"><a href=\"https:\/\/tinanjsc.com\/hoat-dong\/khanh-thanh-cau-vinh-thai-740.html\"><img decoding=\"async\" src=\"https:\/\/tinanjsc.com\/upload\/news\/717314967963.jpg\" alt=\"INAUGURATION OF VINH THAI BRIDGE\"><\/a><\/div>\n<\/div>\n<div class=\"item rtl\">\n<div class=\"content-left wow bounceInLeft\" data-wow-delay=\"1s\">\n<h3>COMMENCER LA CONSTRUCTION<\/h3>\n<div class=\"text bd-left\">\n<p>Le 31 mai 2020, au hameau Phu Trach 1, commune Cam Son, district Mo Cay Nam, province Ben Tre. Tin An JSC \u00e9tait pr\u00e9sent pour organiser la c\u00e9r\u00e9monie d'inauguration du \"C\u1ea7u N\u1ed1i Y\u00eau Th\u01b0\u01a1ng\" n \u00b0 57. Avec un co\u00fbt de construction total de 3 milliards 500 millions de VND<\/p>\n<\/div>\n<\/div>\n<div class=\"content-right wow bounceInRight\" data-wow-delay=\"1.5s\"><a href=\"https:\/\/tinanjsc.com\/hoat-dong\/khoi-cong-xay-dung-cau-noi-yeu-thuong-so-57-695.html\"><img decoding=\"async\" src=\"https:\/\/tinanjsc.com\/upload\/news\/032776195093.jpg\" alt=\" STARTING CONSTRUCTION \"><\/a><\/div>\n<\/div>\n<div class=\"item\">\n<div class=\"content-left wow bounceInLeft\" data-wow-delay=\"1s\">\n<h3>C\u00c9R\u00c9MONIE D'OUVERTURE DU PONT DE TIN KIM 01<\/h3>\n<div class=\"text bd-left\">\n<p>Adieu aux autorit\u00e9s et aux habitants de la commune de Hoa Tan, ville de Ca Mau avec la promesse de rendre visite \u00e0 tout le monde dans une journ\u00e9e proche, dans l'apr\u00e8s-midi du 27 avril 2019, la d\u00e9l\u00e9gation s'est d\u00e9plac\u00e9e au hameau de Huu Thoi, quartier Bien Bach Dong, Le district de Thoi Binh, province de Ca Mau organisera la c\u00e9r\u00e9monie d'inauguration du pont Tin Kim 01<\/p>\n<\/div>\n<\/div>\n<div class=\"content-right wow bounceInRight\" data-wow-delay=\"1.5s\"><a href=\"https:\/\/tinanjsc.com\/hoat-dong\/le-khanh-thanh-cau-tin-kim-01-743.html\"><img decoding=\"async\" src=\"https:\/\/tinanjsc.com\/upload\/news\/582720675917.jpg\" alt=\"OPENING CEREMONY OF TIN KIM BRIDGE 01\"><\/a><\/div>\n<\/div>\n<div class=\"item rtl\">\n<div class=\"content-left wow bounceInLeft\" data-wow-delay=\"1s\">\n<h3>C\u00c9R\u00c9MONIE D'OUVERTURE DU PONT DE TIN KIM 02<\/h3>\n<div class=\"text bd-left\">\n<p dir=\"rtl\">Dans la matin\u00e9e du dimanche 12 mai 2019, TIN AN JSC &amp; TIN KIM PLASTIC JOINT STOCK COMPANY sont retourn\u00e9s au Hameau 21, Commune de Phong Tan, Commune de Gia Rai, Province de Bac Lieu, pour se joindre \u00e0 l'autorit\u00e9 locale et \u00e0 la population locale pour organiser l'inauguration c\u00e9r\u00e9monie du pont Tin Kim 02 apr\u00e8s pr\u00e8s de 3 mois de construction. Toute la fatigue des membres de la d\u00e9l\u00e9gation, apr\u00e8s un long chemin, a sembl\u00e9 dispara\u00eetre, en voyant l'enthousiasme des gens lorsque le pont de r\u00eave \u00e9tait termin\u00e9 et pr\u00eat \u00e0 \u00eatre utilis\u00e9.<\/p>\n<\/div>\n<\/div>\n<div class=\"content-right wow bounceInRight\" data-wow-delay=\"1.5s\"><a href=\"https:\/\/tinanjsc.com\/hoat-dong\/le-khanh-thanh-cau-tin-kim-02-cau-tu-tam-25-742.html\"><img decoding=\"async\" src=\"https:\/\/tinanjsc.com\/upload\/news\/711176061090.jpg\" alt=\"OPENING CEREMONY OF TIN KIM BRIDGE 02\"><\/a><\/div>\n<\/div>\n<div class=\"item\">\n<div class=\"content-left wow bounceInLeft\" data-wow-delay=\"1s\">\n<h3>C\u00c9R\u00c9MONIE D'OUVERTURE DU PONT DE TIN KIM 03<\/h3>\n<div class=\"text bd-left\">\n<p dir=\"rtl\">Tenir une promesse faite aux habitants du hameau An My, commune Hoa An, district Cho Moi, province An Giang, le 21 septembre 2019, le groupe de volontaires Tu Tam (TNTT) est revenu \u00e0 cet endroit pour c\u00e9l\u00e9brer avec des proches, lorsque le pont Tin Kim 03 \u2013 apr\u00e8s plus d'1 mois et demi de construction, les berges ont encha\u00een\u00e9 au rythme des berges, apportant gaiet\u00e9 et gaiet\u00e9 aux habitants, notamment aux \u00e9tudiants du quartier.<\/p>\n<\/div>\n<\/div>\n<div class=\"content-right wow bounceInRight\" data-wow-delay=\"1.5s\"><a href=\"https:\/\/tinanjsc.com\/hoat-dong\/le-khanh-thanh-cau-tin-kim-03-cau-tu-tam-26-741.html\"><img decoding=\"async\" src=\"https:\/\/tinanjsc.com\/upload\/news\/659555182655.jpg\" alt=\"OPENING CEREMONY OF TIN KIM BRIDGE 03\"><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"about-head leader-head wow fadeInUp\" data-wow-offset=\"0\" data-wow-duration=\"1\" data-wow-delay=\"0.2s\">\n<div class=\"container\">\n<h2><span class=\"bd-right\"> DIRECTION DE L'ENTREPRISE<\/span><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gap-element\" style=\"display:block; height:auto; padding-top:30px\"><\/div>\n<div class=\"row\"  id=\"row-549547142\">\n<div class=\"col medium-6 small-12 large-6\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image\" style=\"width:48%;\">\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img width=\"1065\" height=\"1065\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/08\/viber_image_2022-07-27_21-38-50-455-2.jpg\" class=\"attachment- size-\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/08\/viber_image_2022-07-27_21-38-50-455-2.jpg 1065w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/08\/viber_image_2022-07-27_21-38-50-455-2-300x300.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/08\/viber_image_2022-07-27_21-38-50-455-2-1024x1024.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/08\/viber_image_2022-07-27_21-38-50-455-2-150x150.jpg 150w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/08\/viber_image_2022-07-27_21-38-50-455-2-768x768.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/08\/viber_image_2022-07-27_21-38-50-455-2-600x600.jpg 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/08\/viber_image_2022-07-27_21-38-50-455-2-100x100.jpg 100w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/08\/viber_image_2022-07-27_21-38-50-455-2-50x50.jpg 50w\" sizes=\"(max-width: 1065px) 100vw, 1065px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.1)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\"><\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                                          <\/span>\n                  <\/h4>\n                     <div class=\"social-icons follow-icons\" >\n    \t    \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t     <\/div>\n\n\t                 \n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<p class=\" translation-block\"><strong><br>\r\nThanh Viet Nguyen<\/strong>&nbsp;has lived, studied and worked in Vietnam all his life. His professional career has mainly concentrated on SPC plastic industry and supplying building materials in the Vietnamese market. He has more than 20 years of successful experience in providing construction materials for multiple projects such as hotels, banks, insurance companies, hospitals, large buildings and residential complexes. Thanh is excited to introduce this amazing SPC flooring solution to the Canadian market.<\/p>\n<\/div><\/div>\n<div class=\"col medium-6 small-12 large-6\"  ><div class=\"col-inner\"  >\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image\" style=\"width:48%;\">\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img width=\"1732\" height=\"2302\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/10\/DSC03906_Original.jpg\" class=\"attachment- size-\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/10\/DSC03906_Original.jpg 1732w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/10\/DSC03906_Original-226x300.jpg 226w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/10\/DSC03906_Original-770x1024.jpg 770w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/10\/DSC03906_Original-768x1021.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/10\/DSC03906_Original-1156x1536.jpg 1156w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/10\/DSC03906_Original-1541x2048.jpg 1541w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/10\/DSC03906_Original-600x797.jpg 600w\" sizes=\"(max-width: 1732px) 100vw, 1732px\" \/>              <div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.1)\"><\/div>           <\/div>\n          <\/div><!-- box-image -->\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\"><\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                                          <\/span>\n                  <\/h4>\n                     <div class=\"social-icons follow-icons\" >\n    \t    \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t     <\/div>\n\n\t                 \n                <\/div><!-- box-text-inner -->\n          <\/div><!-- box-text -->\n    <\/div><!-- .box  -->\n\n    \n    \n<p class=\" translation-block\">Je m'appelle <strong>Nhut Nguyen<\/strong>\u00a0et les gens m'appelaient <strong>Rose Nguyen.<\/strong><br>J'ai grandi au Vietnam et je suis arriv\u00e9e au Canada \u00e0 l'adolescence. J'ai termin\u00e9 mes \u00e9tudes secondaires au Canada et j'ai fr\u00e9quent\u00e9 le Coll\u00e8ge Algonquin pour obtenir un dipl\u00f4me en g\u00e9nie \u00e9lectrique. Je suis entrepreneur et j'ai eu ma propre entreprise depuis que j'ai termin\u00e9 mes \u00e9tudes. Lorsque j'ai d\u00e9marr\u00e9 l'entreprise de rev\u00eatements de sol, j'ai capitalis\u00e9 sur ma compr\u00e9hension des cultures et des environnements d'affaires vietnamiens et canadiens, mon exp\u00e9rience en entrepreneuriat et mon bagage technique. Le rev\u00eatement de sol est une ligne de travail qui me passionne et je suis ravi de partager ma passion pour le rev\u00eatement de sol avec mes clients nouveaux et existants.<\/p>\n<\/div><\/div>\n<\/div>\n<div class=\"gap-element\" style=\"display:block; height:auto; padding-top:30px\"><\/div>\n\n\t\t<div class=\"tabbed-content\">\n\t\t\t\n\t\t\t<ul class=\"nav nav-tabs nav-uppercase nav-size-normal nav-center\"><li class=\"tab active has-icon\"><a href=\"#tab_album-1\"><span>Album 1<\/span><\/a><\/li>\n<li class=\"tab has-icon\"><a href=\"#tab_album-2\"><span>Album 2<\/span><\/a><\/li><\/ul><div class=\"tab-panels\"><div class=\"panel active entry-content\" id=\"tab_album-1\">\n\n  \n    <div class=\"row large-columns-8 medium-columns-3 small-columns-2\">\n          <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_093336-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"1020\" height=\"765\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_093336-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_093336-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_093336-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_093336-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_093336-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_093336-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_093336-600x450.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133450-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"1020\" height=\"765\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133450-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133450-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133450-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133450-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133450-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133450-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133450-600x450.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133518-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"1020\" height=\"765\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133518-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133518-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133518-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133518-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133518-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133518-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133518-600x450.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133544-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"1020\" height=\"765\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133544-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133544-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133544-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133544-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133544-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133544-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133544-600x450.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133618-768x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"768\" height=\"1024\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133618-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133618-768x1024.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133618-225x300.jpg 225w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133618-1152x1536.jpg 1152w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133618-1536x2048.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133618-600x800.jpg 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133618-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133643-768x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"768\" height=\"1024\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133643-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133643-768x1024.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133643-225x300.jpg 225w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133643-1152x1536.jpg 1152w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133643-1536x2048.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133643-600x800.jpg 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133643-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133710-768x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"768\" height=\"1024\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133710-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133710-768x1024.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133710-225x300.jpg 225w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133710-1152x1536.jpg 1152w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133710-1536x2048.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133710-600x800.jpg 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133710-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133734-768x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"768\" height=\"1024\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133734-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133734-768x1024.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133734-225x300.jpg 225w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133734-1152x1536.jpg 1152w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133734-1536x2048.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133734-600x800.jpg 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133734-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133810-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"1020\" height=\"765\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133810-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133810-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133810-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133810-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133810-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133810-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133810-600x450.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133849-768x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"768\" height=\"1024\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133849-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133849-768x1024.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133849-225x300.jpg 225w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133849-1152x1536.jpg 1152w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133849-1536x2048.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133849-600x800.jpg 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133849-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133912-768x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"768\" height=\"1024\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133912-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133912-768x1024.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133912-225x300.jpg 225w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133912-1152x1536.jpg 1152w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133912-1536x2048.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133912-600x800.jpg 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133912-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133938-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"1020\" height=\"765\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133938-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133938-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133938-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133938-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133938-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133938-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_133938-600x450.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134013-768x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"768\" height=\"1024\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134013-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134013-768x1024.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134013-225x300.jpg 225w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134013-1152x1536.jpg 1152w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134013-1536x2048.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134013-600x800.jpg 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134013-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134043-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"1020\" height=\"765\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134043-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134043-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134043-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134043-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134043-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134043-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134043-600x450.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134107-768x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"768\" height=\"1024\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134107-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134107-768x1024.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134107-225x300.jpg 225w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134107-1152x1536.jpg 1152w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134107-1536x2048.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134107-600x800.jpg 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134107-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134131-768x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"768\" height=\"1024\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134131-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134131-768x1024.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134131-225x300.jpg 225w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134131-1152x1536.jpg 1152w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134131-1536x2048.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134131-600x800.jpg 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134131-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134148-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"1020\" height=\"765\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134148-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134148-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134148-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134148-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134148-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134148-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134148-600x450.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134204-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"1020\" height=\"765\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134204-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134204-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134204-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134204-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134204-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134204-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134204-600x450.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134322-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"1020\" height=\"765\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134322-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134322-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134322-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134322-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134322-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134322-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134322-600x450.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134339-768x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"768\" height=\"1024\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134339-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134339-768x1024.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134339-225x300.jpg 225w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134339-1152x1536.jpg 1152w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134339-1536x2048.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134339-600x800.jpg 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134339-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134427-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"1020\" height=\"765\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134427-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134427-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134427-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134427-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134427-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134427-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134427-600x450.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134500-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"1020\" height=\"765\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134500-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134500-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134500-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134500-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134500-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134500-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134500-600x450.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134527-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img width=\"1020\" height=\"765\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134527-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"748,749,750,751,752,753,754,755,756,757,758,759,760,761,762,763,764,765,766,767,768,769,770\" columns=\"8\" image_height=\"100%\" image_size=\"large\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134527-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134527-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134527-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134527-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134527-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/20200506_134527-600x450.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n         <\/div>\n<\/div>\n<div class=\"panel entry-content\" id=\"tab_album-2\">\n\n  \n    <div class=\"row large-columns-8 medium-columns-3 small-columns-2\">\n          <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-1-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"225\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-1-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"771,772,773,774,775,776,777,778,779,780,781,782,783\" columns=\"8\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-1-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-1-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-1-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-1-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-1-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-1-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-2-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"225\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-2-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"771,772,773,774,775,776,777,778,779,780,781,782,783\" columns=\"8\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-2-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-2-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-2-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-2-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-2-600x450.jpg 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-2.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-3-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"225\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-3-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"771,772,773,774,775,776,777,778,779,780,781,782,783\" columns=\"8\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-3-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-3-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-3-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-3-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-3-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-3-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-4-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"225\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-4-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"771,772,773,774,775,776,777,778,779,780,781,782,783\" columns=\"8\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-4-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-4-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-4-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-4-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-4-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-4-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-5-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"225\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-5-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"771,772,773,774,775,776,777,778,779,780,781,782,783\" columns=\"8\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-5-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-5-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-5-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-5-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-5-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-5-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-6-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"225\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-6-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"771,772,773,774,775,776,777,778,779,780,781,782,783\" columns=\"8\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-6-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-6-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-6-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-6-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-6-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-6-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-7-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"225\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-7-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"771,772,773,774,775,776,777,778,779,780,781,782,783\" columns=\"8\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-7-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-7-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-7-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-7-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-7-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-7-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-8-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"225\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-8-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"771,772,773,774,775,776,777,778,779,780,781,782,783\" columns=\"8\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-8-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-8-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-8-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-8-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-8-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-8-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-9-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"225\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-9-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"771,772,773,774,775,776,777,778,779,780,781,782,783\" columns=\"8\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-9-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-9-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-9-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-9-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-9-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-9-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-10-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"225\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-10-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"771,772,773,774,775,776,777,778,779,780,781,782,783\" columns=\"8\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-10-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-10-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-10-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-10-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-10-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-10-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-11-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"225\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-11-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"771,772,773,774,775,776,777,778,779,780,781,782,783\" columns=\"8\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-11-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-11-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-11-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-11-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-11-600x450.jpg 600w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-11.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-12-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"225\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-12-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"771,772,773,774,775,776,777,778,779,780,781,782,783\" columns=\"8\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-12-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-12-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-12-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-12-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-12-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-12-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-13-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"225\" src=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-13-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"771,772,773,774,775,776,777,778,779,780,781,782,783\" columns=\"8\" srcset=\"https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-13-300x225.jpg 300w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-13-1024x768.jpg 1024w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-13-768x576.jpg 768w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-13-1536x1152.jpg 1536w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-13-2048x1536.jpg 2048w, https:\/\/tnspcflooring.ca\/wp-content\/uploads\/2022\/06\/Pic-13-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\">\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n         <\/div>\n<\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>ABOUT TIN AN JSC TIN AN JSC&nbsp;was established in late 2016, with the charter capital of 250 Billion Vietnam dongs, the total ground area up to 60,000&nbsp;m2. The company\u2019s strategic products include&nbsp;SPC&nbsp;Flooring, Products for Export Processing to USA market, Steel Core Plastic\/ Aluminum Doors &amp;Windows, Facade, providing construction solutions and services, installation for construction works [&hellip;]","protected":false},"author":1,"featured_media":962,"parent":892,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"ngg_post_thumbnail":0},"_links":{"self":[{"href":"https:\/\/tnspcflooring.ca\/fr\/wp-json\/wp\/v2\/pages\/19"}],"collection":[{"href":"https:\/\/tnspcflooring.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tnspcflooring.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tnspcflooring.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tnspcflooring.ca\/fr\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":132,"href":"https:\/\/tnspcflooring.ca\/fr\/wp-json\/wp\/v2\/pages\/19\/revisions"}],"predecessor-version":[{"id":1112,"href":"https:\/\/tnspcflooring.ca\/fr\/wp-json\/wp\/v2\/pages\/19\/revisions\/1112"}],"up":[{"embeddable":true,"href":"https:\/\/tnspcflooring.ca\/fr\/wp-json\/wp\/v2\/pages\/892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tnspcflooring.ca\/fr\/wp-json\/wp\/v2\/media\/962"}],"wp:attachment":[{"href":"https:\/\/tnspcflooring.ca\/fr\/wp-json\/wp\/v2\/media?parent=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}